{"id":363,"count":37,"description":"","link":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/","name":"Federal Agencies","slug":"federal-agencies","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Federal Agencies Archives - Beyond Pesticides Daily News Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federal Agencies Archives - Beyond Pesticides Daily News Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Pesticides Daily News Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ByondPesticides\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/\",\"url\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/\",\"name\":\"Federal Agencies Archives - Beyond Pesticides Daily News Blog\",\"isPartOf\":{\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Federal Agencies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/#website\",\"url\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/\",\"name\":\"Beyond Pesticides Daily News Blog\",\"description\":\"News on Pesticide Science, Policy and Activism\",\"publisher\":{\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/#organization\",\"name\":\"Beyond Pesticides\",\"url\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-content\/uploads\/2023\/05\/BeyondPesticides-Logo-Stacked-scaled.jpg\",\"contentUrl\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-content\/uploads\/2023\/05\/BeyondPesticides-Logo-Stacked-scaled.jpg\",\"width\":2560,\"height\":2501,\"caption\":\"Beyond Pesticides\"},\"image\":{\"@id\":\"https:\/\/beyondpesticides.org\/dailynewsblog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beyondpesticides\",\"https:\/\/x.com\/ByondPesticides\",\"https:\/\/www.instagram.com\/beyondpesticides\/?hl=en\",\"https:\/\/www.linkedin.com\/company\/beyond-pesticides\",\"https:\/\/www.youtube.com\/user\/bpncamp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federal Agencies Archives - Beyond Pesticides Daily News Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/","og_locale":"en_US","og_type":"article","og_title":"Federal Agencies Archives - Beyond Pesticides Daily News Blog","og_url":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/","og_site_name":"Beyond Pesticides Daily News Blog","twitter_card":"summary_large_image","twitter_site":"@ByondPesticides","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/","url":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/","name":"Federal Agencies Archives - Beyond Pesticides Daily News Blog","isPartOf":{"@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/#website"},"breadcrumb":{"@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/category\/federal-agencies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondpesticides.org\/dailynewsblog\/"},{"@type":"ListItem","position":2,"name":"Federal Agencies"}]},{"@type":"WebSite","@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/#website","url":"https:\/\/beyondpesticides.org\/dailynewsblog\/","name":"Beyond Pesticides Daily News Blog","description":"News on Pesticide Science, Policy and Activism","publisher":{"@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondpesticides.org\/dailynewsblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/#organization","name":"Beyond Pesticides","url":"https:\/\/beyondpesticides.org\/dailynewsblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/#\/schema\/logo\/image\/","url":"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-content\/uploads\/2023\/05\/BeyondPesticides-Logo-Stacked-scaled.jpg","contentUrl":"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-content\/uploads\/2023\/05\/BeyondPesticides-Logo-Stacked-scaled.jpg","width":2560,"height":2501,"caption":"Beyond Pesticides"},"image":{"@id":"https:\/\/beyondpesticides.org\/dailynewsblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondpesticides","https:\/\/x.com\/ByondPesticides","https:\/\/www.instagram.com\/beyondpesticides\/?hl=en","https:\/\/www.linkedin.com\/company\/beyond-pesticides","https:\/\/www.youtube.com\/user\/bpncamp"]}]}},"_links":{"self":[{"href":"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-json\/wp\/v2\/categories\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/beyondpesticides.org\/dailynewsblog\/wp-json\/wp\/v2\/posts?categories=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}